{"id":1289,"count":1,"description":"","link":"http:\/\/blog.proofs.de\/lv\/schlagwort\/film\/","name":"Filma","slug":"filma","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"TuXxyRwxcEg2-WfOaQ8vScWQh3-uBAnxXmY7g3GT90A\" \/>\n\t<link rel=\"canonical\" href=\"http:\/\/blog.proofs.de\/lv\/schlagwort\/film\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\n\t\t<meta name=\"seobility\" content=\"593a8578143db71543f014978c690d47\">\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/blog.proofs.de\\\/lv\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1289\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/blog.proofs.de\\\/lv#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/blog.proofs.de\\\/lv\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/blog.proofs.de\\\/lv\\\/schlagwort\\\/film\\\/#listItem\",\"name\":\"Film\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/blog.proofs.de\\\/lv\\\/schlagwort\\\/film\\\/#listItem\",\"position\":2,\"name\":\"Film\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/blog.proofs.de\\\/lv#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/blog.proofs.de\\\/lv\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1289\\\/#collectionpage\",\"url\":\"http:\\\/\\\/blog.proofs.de\\\/lv\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1289\\\/\",\"name\":\"Film | Proof.de\",\"inLanguage\":\"lv\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/blog.proofs.de\\\/lv\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/blog.proofs.de\\\/lv\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1289\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/blog.proofs.de\\\/lv\\\/#organization\",\"name\":\"Proof GmbH\",\"description\":\"Farbverbindlicher Proof, Farbproof, Digitalproof und Online-Proof.\",\"url\":\"http:\\\/\\\/blog.proofs.de\\\/lv\\\/\",\"telephone\":\"+4970717952740\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog1.proofen.de\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo_proof_rgb_mit_balken_250px.png\",\"@id\":\"http:\\\/\\\/blog.proofs.de\\\/lv\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1289\\\/#organizationLogo\"},\"image\":{\"@id\":\"http:\\\/\\\/blog.proofs.de\\\/lv\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1289\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Proof.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/proof.de\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@proof_de\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCk80fQVQ25wC9wu3SywB-Nw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/proof-de\"]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/blog.proofs.de\\\/lv\\\/#website\",\"url\":\"http:\\\/\\\/blog.proofs.de\\\/lv\\\/\",\"name\":\"Proof.de\",\"description\":\"Farbverbindlicher Proof, Farbproof, Digitalproof und Online-Proof.\",\"inLanguage\":\"lv\",\"publisher\":{\"@id\":\"http:\\\/\\\/blog.proofs.de\\\/lv\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Film | Proof.de","description":"","canonical_url":"http:\/\/blog.proofs.de\/lv\/schlagwort\/film\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"TuXxyRwxcEg2-WfOaQ8vScWQh3-uBAnxXmY7g3GT90A","miscellaneous":"&lt;meta name=\"seobility\" content=\"593a8578143db71543f014978c690d47\"&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"http:\/\/blog.proofs.de\/lv\/wp-json\/wp\/v2\/tags\/1289\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/blog.proofs.de\/lv#listItem","position":1,"name":"Home","item":"http:\/\/blog.proofs.de\/lv","nextItem":{"@type":"ListItem","@id":"http:\/\/blog.proofs.de\/lv\/schlagwort\/film\/#listItem","name":"Film"}},{"@type":"ListItem","@id":"http:\/\/blog.proofs.de\/lv\/schlagwort\/film\/#listItem","position":2,"name":"Film","previousItem":{"@type":"ListItem","@id":"http:\/\/blog.proofs.de\/lv#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"http:\/\/blog.proofs.de\/lv\/wp-json\/wp\/v2\/tags\/1289\/#collectionpage","url":"http:\/\/blog.proofs.de\/lv\/wp-json\/wp\/v2\/tags\/1289\/","name":"Film | Proof.de","inLanguage":"lv","isPartOf":{"@id":"http:\/\/blog.proofs.de\/lv\/#website"},"breadcrumb":{"@id":"http:\/\/blog.proofs.de\/lv\/wp-json\/wp\/v2\/tags\/1289\/#breadcrumblist"}},{"@type":"Organization","@id":"http:\/\/blog.proofs.de\/lv\/#organization","name":"Proof GmbH","description":"Farbverbindlicher Proof, Farbproof, Digitalproof und Online-Proof.","url":"http:\/\/blog.proofs.de\/lv\/","telephone":"+4970717952740","logo":{"@type":"ImageObject","url":"https:\/\/blog1.proofen.de\/wp-content\/uploads\/2019\/09\/logo_proof_rgb_mit_balken_250px.png","@id":"http:\/\/blog.proofs.de\/lv\/wp-json\/wp\/v2\/tags\/1289\/#organizationLogo"},"image":{"@id":"http:\/\/blog.proofs.de\/lv\/wp-json\/wp\/v2\/tags\/1289\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Proof.de\/","https:\/\/www.instagram.com\/proof.de\/","https:\/\/www.tiktok.com\/@proof_de","https:\/\/www.youtube.com\/channel\/UCk80fQVQ25wC9wu3SywB-Nw","https:\/\/www.linkedin.com\/company\/proof-de"]},{"@type":"WebSite","@id":"http:\/\/blog.proofs.de\/lv\/#website","url":"http:\/\/blog.proofs.de\/lv\/","name":"Proof.de","description":"Farbverbindlicher Proof, Farbproof, Digitalproof und Online-Proof.","inLanguage":"lv","publisher":{"@id":"http:\/\/blog.proofs.de\/lv\/#organization"}}]}},"_links":{"self":[{"href":"http:\/\/blog.proofs.de\/lv\/wp-json\/wp\/v2\/tags\/1289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/blog.proofs.de\/lv\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/blog.proofs.de\/lv\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/blog.proofs.de\/lv\/wp-json\/wp\/v2\/posts?tags=1289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}