{"id":2923,"date":"2020-03-30T16:48:23","date_gmt":"2020-03-30T14:48:23","guid":{"rendered":"https:\/\/www.proof.de\/?post_type=encyclopedia&#038;p=2923"},"modified":"2024-09-19T01:42:57","modified_gmt":"2024-09-18T23:42:57","slug":"gamut-mapping","status":"publish","type":"encyclopedia","link":"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut-mapping\/","title":{"rendered":"Mappage de gamut"},"content":{"rendered":"<div class=\"kk-star-ratings kksr-auto kksr-align-right kksr-valign-top\" data-payload='{\"align\":\"right\",\"id\":\"2923\",\"slug\":\"default\",\"valign\":\"top\",\"ignore\":\"\",\"reference\":\"auto\",\"class\":\"\",\"count\":\"0\",\"legendonly\":\"\",\"readonly\":\"\",\"score\":\"0\",\"starsonly\":\"\",\"best\":\"5\",\"gap\":\"5\",\"greet\":\"Jetzt bewerten\",\"legend\":\"0\\\/5 - (0 vote)\",\"size\":\"24\",\"title\":\"Gamut-Mapping\",\"width\":\"0\",\"_legend\":\"{score}\\\/{best} - ({count} {votes})\",\"font_factor\":\"1.25\"}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">\u00c9valuer maintenant<\/span>\n    <\/div>\n    <\/div>\n<p><a href=\"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut\/\" target=\"_self\" title=\"Le gamut (ou gamme de couleurs) est l&#039;ensemble des couleurs d&#039;un espace colorim\u00e9trique qui peuvent \u00eatre reconnues par un appareil (appareil photo, scanner) ou reproduites (imprimante, moniteur). Elle est repr\u00e9sent\u00e9e sous la forme d&#039;un corps de couleur.\" class=\"encyclopedia\">Gamut<\/a>-mapping (en allemand. : <a href=\"https:\/\/blog.proofs.de\/fr\/lexikon\/farbraum\/\" target=\"_self\" title=\"L&#039;espace colorim\u00e9trique est bas\u00e9 sur un mod\u00e8le de couleurs et est son application concr\u00e8te \u00e0 une m\u00e9thode de reproduction des couleurs (imprimante, \u00e9cran, etc.). Il contient donc toutes les couleurs qui peuvent \u00eatre effectivement repr\u00e9sent\u00e9es avec cette m\u00e9thode et les mat\u00e9riaux correspondants.\" class=\"encyclopedia\">Espace colorim\u00e9trique<\/a>transformation, ajustement de l'espace colorim\u00e9trique) d\u00e9signe le processus par lequel les couleurs d'une image ou d'un graphique sont ajust\u00e9es de mani\u00e8re \u00e0 rester dans les limites de l'espace colorim\u00e9trique affichable. <a href=\"https:\/\/blog.proofs.de\/fr\/lexikon\/farbumfang\/\" target=\"_self\" title=\"La gamme de couleurs (ou gamut) est l&#039;ensemble des couleurs d&#039;un espace colorim\u00e9trique qui peut \u00eatre reconnu par un appareil (appareil photo, scanner) ou reproduit (imprimante, moniteur). Elle est repr\u00e9sent\u00e9e sous la forme d&#039;un corps de couleur.\" class=\"encyclopedia\">Gamme de couleurs<\/a>s (gamut) d'un appareil ou d'un support sp\u00e9cifique. Comme les p\u00e9riph\u00e9riques tels que les imprimantes, les moniteurs ou les appareils photo ont des gammes de couleurs diff\u00e9rentes, il arrive souvent que les couleurs affich\u00e9es sur le moniteur, par exemple, en <a href=\"https:\/\/blog.proofs.de\/fr\/lexikon\/srgb\/\" target=\"_self\" title=\"sRGB est l&#039;espace colorim\u00e9trique RVB le plus r\u00e9pandu. sRGB est l&#039;espace colorim\u00e9trique standard de tous les appareils photo num\u00e9riques et scanners bon march\u00e9. Presque tous les fichiers RVB 8 bits sans indicateur de profil sont conformes \u00e0 sRVB.\" class=\"encyclopedia\">sRGB<\/a> sur un support cible, tel qu'un disque dur int\u00e9gr\u00e9. <a href=\"https:\/\/blog.proofs.de\/fr\/lexikon\/cmyk\/\" target=\"_self\" title='CMYK d\u00e9signe les quatre couleurs d&#039;impression cyan, magenta, jaune et &quot;key&quot; (noir ou partie noire).' class=\"encyclopedia\">CMYK<\/a> ne peuvent pas \u00eatre repr\u00e9sent\u00e9es sur le papier imprim\u00e9. Le gamut mapping permet d'ajuster ou de \"mapper\" correctement ces couleurs afin de les reproduire le plus fid\u00e8lement possible.<\/p>\n<p>Le gamut mapping compare les couleurs \u00e0 la gamme de couleurs du support cible. Si les couleurs sont en dehors du gamut cible et ne peuvent donc pas \u00eatre affich\u00e9es, elles sont remplac\u00e9es par des couleurs qui se situent dans le gamut du p\u00e9riph\u00e9rique cible. Cela peut se faire de diff\u00e9rentes mani\u00e8res :<\/p>\n<ul>\n<li>Sur le site <strong>Clipping<\/strong> les couleurs situ\u00e9es en dehors du gamut sont remplac\u00e9es par les couleurs affichables les plus proches. <a href=\"https:\/\/blog.proofs.de\/fr\/lexikon\/beschnitt\/\" target=\"_self\" title=\"Le fond perdu est la zone qui est imprim\u00e9e mais qui est coup\u00e9e \u00e0 la fin de l&#039;impression.\" class=\"encyclopedia\">rognage<\/a>de l'image. Cependant, cela entra\u00eene une perte de d\u00e9tails dans les zones tr\u00e8s satur\u00e9es.<\/li>\n<li>Lors de la <strong>Compression (Compression) <\/strong>la totalit\u00e9 du gamut source est transf\u00e9r\u00e9e proportionnellement au gamut cible. Cela permet d'exploiter pleinement l'espace colorim\u00e9trique du p\u00e9riph\u00e9rique cible, mais les couleurs peuvent sembler un peu moins vives, car toutes les couleurs sont l\u00e9g\u00e8rement d\u00e9cal\u00e9es.<\/li>\n<li>Lors de la <strong>Adaptation perceptuelle<\/strong> tente de pr\u00e9server l'impression visuelle de l'image en ajustant les couleurs de mani\u00e8re \u00e0 ce qu'elles soient aussi similaires que possible pour l'\u0153il humain, m\u00eame si les teintes sont en fait l\u00e9g\u00e8rement diff\u00e9rentes.<\/li>\n<\/ul>\n<p>Le gamut mapping est une \u00e9tape indispensable dans l'ajustement des couleurs entre diff\u00e9rents supports ou p\u00e9riph\u00e9riques. Sans ce processus, des d\u00e9tails et des couleurs importants de l'image pourraient \u00eatre perdus, ce qui entra\u00eenerait une baisse de la qualit\u00e9 de l'image et de la pr\u00e9cision des couleurs. Une photographie num\u00e9rique peut afficher des couleurs brillantes sur un moniteur, alors que l'imprimante peut ne pas \u00eatre en mesure de reproduire les m\u00eames couleurs avec pr\u00e9cision. Le gamut mapping permet de s'assurer que l'image imprim\u00e9e est aussi proche que possible de la version num\u00e9rique.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>dt : transformation de l'espace colorim\u00e9trique, ajustement de l'espace colorim\u00e9trique<br \/>\nConversion des valeurs chromatiques d'un espace colorim\u00e9trique (par ex. sRGB \u00e0 l'\u00e9cran) en un autre espace colorim\u00e9trique (par ex. CMYK \u00e0 l'impression), de sorte que la reproduction des couleurs reste aussi identique que possible.<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-2923","encyclopedia","type-encyclopedia","status-publish","hentry","no-featured-image-padding"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Gamut-Mapping hei\u00dft auf deutsch.: Farbraumtransformation, Farbraumanpassung, also die Anpassung von einem Farbraum (z.B. sRGB) auf einen anderen (z.B. CMYK).\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Matthias Betz\"\/>\n\t<meta name=\"google-site-verification\" content=\"TuXxyRwxcEg2-WfOaQ8vScWQh3-uBAnxXmY7g3GT90A\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut-mapping\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\n\t\t<meta name=\"seobility\" content=\"593a8578143db71543f014978c690d47\">\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Proof.de | Alles zu Proof, Farbmanagement, Grafik, Messtechnik &amp; Co.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Definition Gamut-Mapping | Lexikon | proof.de\" \/>\n\t\t<meta property=\"og:description\" content=\"Gamut-Mapping hei\u00dft auf deutsch.: Farbraumtransformation, Farbraumanpassung, also die Anpassung von einem Farbraum (z.B. sRGB) auf einen anderen (z.B. CMYK).\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut-mapping\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/blog1.proofen.de\/wp-content\/uploads\/2020\/04\/proof_background.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/blog1.proofen.de\/wp-content\/uploads\/2020\/04\/proof_background.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-03-30T14:48:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-09-18T23:42:57+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Proof.de\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Definition Gamut-Mapping | Lexikon | proof.de\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Gamut-Mapping hei\u00dft auf deutsch.: Farbraumtransformation, Farbraumanpassung, also die Anpassung von einem Farbraum (z.B. sRGB) auf einen anderen (z.B. CMYK).\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/blog1.proofen.de\/wp-content\/uploads\/2020\/04\/proof_background.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/lexikon\\\/gamut-mapping\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.proofs.de\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/lexikon\\\/#listItem\",\"name\":\"Lexikon\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/lexikon\\\/#listItem\",\"position\":2,\"name\":\"Lexikon\",\"item\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/lexikon\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/lexikon\\\/gamut-mapping\\\/#listItem\",\"name\":\"Gamut-Mapping\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/lexikon\\\/gamut-mapping\\\/#listItem\",\"position\":3,\"name\":\"Gamut-Mapping\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/lexikon\\\/#listItem\",\"name\":\"Lexikon\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/#organization\",\"name\":\"Proof GmbH\",\"description\":\"Farbverbindlicher Proof, Farbproof, Digitalproof und Online-Proof.\",\"url\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/\",\"telephone\":\"+4970717952740\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog1.proofen.de\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo_proof_rgb_mit_balken_250px.png\",\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/lexikon\\\/gamut-mapping\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/lexikon\\\/gamut-mapping\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Proof.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/proof.de\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@proof_de\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCk80fQVQ25wC9wu3SywB-Nw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/proof-de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/author\\\/mbetz\\\/#author\",\"url\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/author\\\/mbetz\\\/\",\"name\":\"Matthias Betz\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/lexikon\\\/gamut-mapping\\\/#authorImage\",\"url\":\"https:\\\/\\\/blog.proofs.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/matthias-betz-e1603934518350-150x150.png\",\"width\":96,\"height\":96,\"caption\":\"Matthias Betz\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/lexikon\\\/gamut-mapping\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/lexikon\\\/gamut-mapping\\\/\",\"name\":\"Definition Gamut-Mapping | Lexikon | proof.de\",\"description\":\"Gamut-Mapping hei\\u00dft auf deutsch.: Farbraumtransformation, Farbraumanpassung, also die Anpassung von einem Farbraum (z.B. sRGB) auf einen anderen (z.B. CMYK).\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/lexikon\\\/gamut-mapping\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/author\\\/mbetz\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/author\\\/mbetz\\\/#author\"},\"datePublished\":\"2020-03-30T16:48:23+02:00\",\"dateModified\":\"2024-09-19T01:42:57+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/\",\"name\":\"Proof.de\",\"description\":\"Farbverbindlicher Proof, Farbproof, Digitalproof und Online-Proof.\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.proofs.de\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"D\u00e9finition du gamut mapping | Lexique | proof.de","description":"Le gamut mapping signifie en fran\u00e7ais : transformation de l'espace colorim\u00e9trique, adaptation de l'espace colorim\u00e9trique, c'est-\u00e0-dire l'adaptation d'un espace colorim\u00e9trique (p.ex. sRGB) \u00e0 un autre (p.ex. CMYK).","canonical_url":"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut-mapping\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"TuXxyRwxcEg2-WfOaQ8vScWQh3-uBAnxXmY7g3GT90A","miscellaneous":"&lt;meta name=\"seobility\" content=\"593a8578143db71543f014978c690d47\"&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut-mapping\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.proofs.de\/fr#listItem","position":1,"name":"Home","item":"https:\/\/blog.proofs.de\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.proofs.de\/fr\/lexikon\/#listItem","name":"Lexikon"}},{"@type":"ListItem","@id":"https:\/\/blog.proofs.de\/fr\/lexikon\/#listItem","position":2,"name":"Lexikon","item":"https:\/\/blog.proofs.de\/fr\/lexikon\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut-mapping\/#listItem","name":"Gamut-Mapping"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.proofs.de\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut-mapping\/#listItem","position":3,"name":"Gamut-Mapping","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.proofs.de\/fr\/lexikon\/#listItem","name":"Lexikon"}}]},{"@type":"Organization","@id":"https:\/\/blog.proofs.de\/fr\/#organization","name":"Proof GmbH","description":"Farbverbindlicher Proof, Farbproof, Digitalproof und Online-Proof.","url":"https:\/\/blog.proofs.de\/fr\/","telephone":"+4970717952740","logo":{"@type":"ImageObject","url":"https:\/\/blog1.proofen.de\/wp-content\/uploads\/2019\/09\/logo_proof_rgb_mit_balken_250px.png","@id":"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut-mapping\/#organizationLogo"},"image":{"@id":"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut-mapping\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Proof.de\/","https:\/\/www.instagram.com\/proof.de\/","https:\/\/www.tiktok.com\/@proof_de","https:\/\/www.youtube.com\/channel\/UCk80fQVQ25wC9wu3SywB-Nw","https:\/\/www.linkedin.com\/company\/proof-de"]},{"@type":"Person","@id":"https:\/\/blog.proofs.de\/fr\/author\/mbetz\/#author","url":"https:\/\/blog.proofs.de\/fr\/author\/mbetz\/","name":"Matthias Betz","image":{"@type":"ImageObject","@id":"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut-mapping\/#authorImage","url":"https:\/\/blog.proofs.de\/wp-content\/uploads\/2020\/10\/matthias-betz-e1603934518350-150x150.png","width":96,"height":96,"caption":"Matthias Betz"}},{"@type":"WebPage","@id":"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut-mapping\/#webpage","url":"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut-mapping\/","name":"Definition Gamut-Mapping | Lexikon | proof.de","description":"Gamut-Mapping hei\u00dft auf deutsch.: Farbraumtransformation, Farbraumanpassung, also die Anpassung von einem Farbraum (z.B. sRGB) auf einen anderen (z.B. CMYK).","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/blog.proofs.de\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut-mapping\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.proofs.de\/fr\/author\/mbetz\/#author"},"creator":{"@id":"https:\/\/blog.proofs.de\/fr\/author\/mbetz\/#author"},"datePublished":"2020-03-30T16:48:23+02:00","dateModified":"2024-09-19T01:42:57+02:00"},{"@type":"WebSite","@id":"https:\/\/blog.proofs.de\/fr\/#website","url":"https:\/\/blog.proofs.de\/fr\/","name":"Proof.de","description":"Farbverbindlicher Proof, Farbproof, Digitalproof und Online-Proof.","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/blog.proofs.de\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Proof.de | Alles zu Proof, Farbmanagement, Grafik, Messtechnik &amp; Co.","og:type":"article","og:title":"Definition Gamut-Mapping | Lexikon | proof.de","og:description":"Gamut-Mapping hei\u00dft auf deutsch.: Farbraumtransformation, Farbraumanpassung, also die Anpassung von einem Farbraum (z.B. sRGB) auf einen anderen (z.B. CMYK).","og:url":"https:\/\/blog.proofs.de\/fr\/lexikon\/gamut-mapping\/","og:image":"https:\/\/blog1.proofen.de\/wp-content\/uploads\/2020\/04\/proof_background.jpg","og:image:secure_url":"https:\/\/blog1.proofen.de\/wp-content\/uploads\/2020\/04\/proof_background.jpg","article:published_time":"2020-03-30T14:48:23+00:00","article:modified_time":"2024-09-18T23:42:57+00:00","article:publisher":"https:\/\/www.facebook.com\/Proof.de\/","twitter:card":"summary","twitter:title":"Definition Gamut-Mapping | Lexikon | proof.de","twitter:description":"Gamut-Mapping hei\u00dft auf deutsch.: Farbraumtransformation, Farbraumanpassung, also die Anpassung von einem Farbraum (z.B. sRGB) auf einen anderen (z.B. CMYK).","twitter:image":"https:\/\/blog1.proofen.de\/wp-content\/uploads\/2020\/04\/proof_background.jpg"},"aioseo_meta_data":{"post_id":"2923","title":"D\u00e9finition #post_title | Lexique | proof.de","description":"Le gamut mapping signifie en fran\u00e7ais : transformation de l'espace colorim\u00e9trique, adaptation de l'espace colorim\u00e9trique, c'est-\u00e0-dire l'adaptation d'un espace colorim\u00e9trique (p.ex. sRGB) \u00e0 un autre (p.ex. CMYK).","keywords":null,"keyphrases":{"focus":{"keyphrase":"Gamut-Mapping","score":82,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":[],"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[],"defaultGraph":"WebPage","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 00:32:57","updated":"2025-06-04 13:58:39","seo_analyzer_scan_date":null,"focus_keyword":"Gamut-Mapping","additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/blog.proofs.de\/fr\/wp-json\/wp\/v2\/encyclopedia\/2923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.proofs.de\/fr\/wp-json\/wp\/v2\/encyclopedia"}],"about":[{"href":"https:\/\/blog.proofs.de\/fr\/wp-json\/wp\/v2\/types\/encyclopedia"}],"author":[{"embeddable":true,"href":"https:\/\/blog.proofs.de\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.proofs.de\/fr\/wp-json\/wp\/v2\/comments?post=2923"}],"version-history":[{"count":6,"href":"https:\/\/blog.proofs.de\/fr\/wp-json\/wp\/v2\/encyclopedia\/2923\/revisions"}],"predecessor-version":[{"id":5822,"href":"https:\/\/blog.proofs.de\/fr\/wp-json\/wp\/v2\/encyclopedia\/2923\/revisions\/5822"}],"wp:attachment":[{"href":"https:\/\/blog.proofs.de\/fr\/wp-json\/wp\/v2\/media?parent=2923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}